{"id":12201,"date":"2024-08-07T09:53:09","date_gmt":"2024-08-07T09:53:09","guid":{"rendered":"https:\/\/blauig-automation.de\/rollenkurve\/"},"modified":"2025-01-23T19:43:53","modified_gmt":"2025-01-23T19:43:53","slug":"rollenkurve","status":"publish","type":"page","link":"https:\/\/blauig-automation.de\/en\/rollenkurve\/","title":{"rendered":"Rollenkurve"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":12065,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-project-detail.php","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-12201","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rollenkurve - blauig-automation.de<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blauig-automation.de\/en\/rollenkurve\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rollenkurve - blauig-automation.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blauig-automation.de\/en\/rollenkurve\/\" \/>\n<meta property=\"og:site_name\" content=\"blauig-automation.de\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T19:43:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blauig-automation.de\/wp-content\/uploads\/2024\/08\/Rollenkurve22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1667\" \/>\n\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blauig-automation.de\/en\/rollenkurve\/\",\"url\":\"https:\/\/blauig-automation.de\/en\/rollenkurve\/\",\"name\":\"Rollenkurve - blauig-automation.de\",\"isPartOf\":{\"@id\":\"https:\/\/blauig-automation.de\/en\/#website\"},\"datePublished\":\"2024-08-07T09:53:09+00:00\",\"dateModified\":\"2025-01-23T19:43:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/blauig-automation.de\/en\/rollenkurve\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blauig-automation.de\/en\/rollenkurve\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blauig-automation.de\/en\/rollenkurve\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blauig-automation.de\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rollenkurve\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blauig-automation.de\/en\/#website\",\"url\":\"https:\/\/blauig-automation.de\/en\/\",\"name\":\"blauig-automation.de\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/blauig-automation.de\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blauig-automation.de\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blauig-automation.de\/en\/#organization\",\"name\":\"Blauig Automation GmbH\",\"url\":\"https:\/\/blauig-automation.de\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/blauig-automation.de\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blauig-automation.de\/wp-content\/uploads\/2024\/08\/Original-3.png\",\"contentUrl\":\"https:\/\/blauig-automation.de\/wp-content\/uploads\/2024\/08\/Original-3.png\",\"width\":4603,\"height\":1855,\"caption\":\"Blauig Automation GmbH\"},\"image\":{\"@id\":\"https:\/\/blauig-automation.de\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rollenkurve - blauig-automation.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blauig-automation.de\/en\/rollenkurve\/","og_locale":"en_US","og_type":"article","og_title":"Rollenkurve - blauig-automation.de","og_url":"https:\/\/blauig-automation.de\/en\/rollenkurve\/","og_site_name":"blauig-automation.de","article_modified_time":"2025-01-23T19:43:53+00:00","og_image":[{"width":1667,"height":528,"url":"https:\/\/blauig-automation.de\/wp-content\/uploads\/2024\/08\/Rollenkurve22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blauig-automation.de\/en\/rollenkurve\/","url":"https:\/\/blauig-automation.de\/en\/rollenkurve\/","name":"Rollenkurve - blauig-automation.de","isPartOf":{"@id":"https:\/\/blauig-automation.de\/en\/#website"},"datePublished":"2024-08-07T09:53:09+00:00","dateModified":"2025-01-23T19:43:53+00:00","breadcrumb":{"@id":"https:\/\/blauig-automation.de\/en\/rollenkurve\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blauig-automation.de\/en\/rollenkurve\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blauig-automation.de\/en\/rollenkurve\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blauig-automation.de\/en\/"},{"@type":"ListItem","position":2,"name":"Rollenkurve"}]},{"@type":"WebSite","@id":"https:\/\/blauig-automation.de\/en\/#website","url":"https:\/\/blauig-automation.de\/en\/","name":"blauig-automation.de","description":"","publisher":{"@id":"https:\/\/blauig-automation.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blauig-automation.de\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/blauig-automation.de\/en\/#organization","name":"Blauig Automation GmbH","url":"https:\/\/blauig-automation.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/blauig-automation.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/blauig-automation.de\/wp-content\/uploads\/2024\/08\/Original-3.png","contentUrl":"https:\/\/blauig-automation.de\/wp-content\/uploads\/2024\/08\/Original-3.png","width":4603,"height":1855,"caption":"Blauig Automation GmbH"},"image":{"@id":"https:\/\/blauig-automation.de\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blauig-automation.de\/en\/wp-json\/wp\/v2\/pages\/12201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blauig-automation.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blauig-automation.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blauig-automation.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blauig-automation.de\/en\/wp-json\/wp\/v2\/comments?post=12201"}],"version-history":[{"count":0,"href":"https:\/\/blauig-automation.de\/en\/wp-json\/wp\/v2\/pages\/12201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blauig-automation.de\/en\/wp-json\/wp\/v2\/media\/12065"}],"wp:attachment":[{"href":"https:\/\/blauig-automation.de\/en\/wp-json\/wp\/v2\/media?parent=12201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}